{"id":1147,"date":"2018-05-20T04:02:57","date_gmt":"2018-05-20T02:02:57","guid":{"rendered":"http:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg.jpg"},"modified":"2018-05-20T04:02:57","modified_gmt":"2018-05-20T02:02:57","slug":"feeding-each-other-jpg","status":"inherit","type":"attachment","link":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/feeding-each-other-jpg\/","title":{"rendered":"feeding-each-other-jpg"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"class_list":["post-1147","attachment","type-attachment","status-inherit","hentry"],"smush":{"stats":{"percent":3.742875467405641476403843626030720770359039306640625,"bytes":3093,"size_before":82637,"size_after":79544,"time":0.070000000000000006661338147750939242541790008544921875,"api_version":"1.0","lossy":false,"keep_exif":true},"sizes":{"thumbnail":{"percent":0,"bytes":0,"size_before":4475,"size_after":4475,"time":0.01000000000000000020816681711721685132943093776702880859375},"medium":{"percent":0,"bytes":0,"size_before":9326,"size_after":9326,"time":0.01000000000000000020816681711721685132943093776702880859375},"sow-carousel-default":{"percent":0,"bytes":0,"size_before":8752,"size_after":8752,"time":0.0200000000000000004163336342344337026588618755340576171875},"full":{"percent":5.1500000000000003552713678800500929355621337890625,"bytes":3093,"size_before":60084,"size_after":56991,"time":0.0299999999999999988897769753748434595763683319091796875}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"178\" src=\"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg-300x178.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg-300x178.jpg 300w, https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg.jpg 676w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"676","height":"402","file":"2018\/05\/feeding-each-other-jpg.jpg","sizes":{"thumbnail":{"file":"feeding-each-other-jpg-150x150.jpg","width":"150","height":"150","mime_type":"image\/jpeg","source_url":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg-150x150.jpg"},"medium":{"file":"feeding-each-other-jpg-300x178.jpg","width":"300","height":"178","mime_type":"image\/jpeg","source_url":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg-300x178.jpg"},"sow-carousel-default":{"file":"feeding-each-other-jpg-272x182.jpg","width":"272","height":"182","mime_type":"image\/jpeg","source_url":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg-272x182.jpg"},"full":{"file":"feeding-each-other-jpg.jpg","width":676,"height":402,"mime_type":"image\/jpeg","source_url":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0"}},"post":null,"source_url":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-content\/uploads\/2018\/05\/feeding-each-other-jpg.jpg","_links":{"self":[{"href":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-json\/wp\/v2\/media\/1147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lfelsalvador.org\/blogs\/chiltepe\/wp-json\/wp\/v2\/comments?post=1147"}]}}